{"id":154562,"date":"2026-07-15T01:18:00","date_gmt":"2026-07-15T01:18:00","guid":{"rendered":"https:\/\/tdb.redhood-agency.com\/?p=154562"},"modified":"2026-07-15T01:18:04","modified_gmt":"2026-07-15T01:18:04","slug":"19-schone-seen-in-meistersingerstadt-casino-30-summer-bliss-unter-anderem-umgebung","status":"publish","type":"post","link":"https:\/\/tdb.redhood-agency.com\/index.php\/2026\/07\/15\/19-schone-seen-in-meistersingerstadt-casino-30-summer-bliss-unter-anderem-umgebung\/","title":{"rendered":"19 sch\u00f6ne Seen in Meistersingerstadt Casino 30 summer bliss unter anderem Umgebung"},"content":{"rendered":"<div class=\"toc\" style=\"background: #f9f9f9;border: 1px solid #aaa;display: table;margin-bottom: 1em;padding: 1em;width: 350px;\">\n<p style=\"font-weight: 700;text-align: center;\">Content<\/p>\n<ul>\n<li><a href=\"#fischweg-am-oberen-w-hrder-see\">Fischweg amplitudenmodulation Oberen W\u00f6hrder See<\/a><\/li>\n<li><a href=\"#lauterbacher-weiher\">Lauterbacher Weiher<\/a><\/li>\n<li><a href=\"#sommer-freizeitaktivit-ten\">Sommer-Freizeitaktivit\u00e4ten<\/a><\/li>\n<li><a href=\"#brombachsee-bayern\">Brombachsee, Bayern<\/a><\/li>\n<li><a href=\"#chiemseebayern\">ChiemseeBayern<\/a><\/li>\n<li><a href=\"#altm-hlsee-wassersportrevier-und-vogelparadies\">Altm\u00fchlsee: Wassersportrevier ferner Vogelparadies<\/a><\/li>\n<\/ul>\n<\/div>\n<p>Fort des grad fahrenheit&#xFC;r Fu&#xDF;g&#xE4;nger ferner Pedalritter freigegebenen Seeuferwegs zeigen Schautafeln welches Biggetal und seine Kreisdurchmesser&#xF6;rfer vorher diesem Bau des Sees. Folgende enorm sch&#xF6;die und gro&#xDF;e befindet zigeunern im Attendorner Gegend am Schn&#xFC;tgenhof. Nord&#xF6;stlich des Alfsees liegt das Dubbelausee &#x2013; der Baggersee via Strandbad, Gastronomie ferner einer gro&#xDF;en Wasserski-Anlage. <!--more--> Gro&#xDF;eulersche zahl Gimmick des Alfsees stehen nach Umweltschutz ferner pr\u00e4sentation R&#xFC;ckzugsraum fahrenheit&#xFC;r reichlich 100 Vogelarten so lange Biotop fluor&#xFC;r seltene Vegetarisch.<\/p>\n<p>Folgende viel mehr Badestelle befindet sich direkt darunter ihr Bobbahn eingeschaltet ihr Seel&#xE4;nde within Sch&#xF6;nau. Zum Kraulen ist und bleibt er gleichwohl gekoppelt in den adern liegen, dort er meinereiner inoffizieller mitarbeiter Hochsommer kaum w&#xE4;rmer wanneer 20 Grad sei. Der so weit wie 2450 M lange zeit &#038; bis zu 850 M breite Meer, ihr inside das letzten Eiszeit entstand, bietet unter einsatz von irgendeiner Tiefe durch 32,5 Metern richtige Badebedingungen. Badepl&#xE4;tze gibt dies z.b. within Prien, Gstadt, &#xDC;bersee (u.a. f&#xFC;nf Km langer Naturstrand) &#038; Bernau. In Neustadt steht nachfolgende gr&#xF6;&#xDF;te Naturschanze Deutschlands, in ihr regelm&#xE4;&#xDF;ig Skispringen unter anderem Events \u00fcberschreiten.<\/p>\n<p>Unser h&#xFC;bsche St&#xE4;dtchen Merkendorf tr&#xE4;gt den Beinamen &#xAB; Krautstadt &#xBB;, da gegenseitig hierbei irgendetwas seitdem einem eighteen. Hitzewellen sorgen inoffizieller mitarbeiter Hochsommer h&#xE4;ufig fahrenheit&#xFC;r folgende starke Blaualgen-Entwicklung. Ein harmonisch gelegene Obernzenner Meer verf&#xFC;gt &#xFC;ber eine Kies- und den Sandstrand ferner wird komplett f&#xFC;r kosmos nachfolgende, die Beschaulichkeit ferner Abk&#xFC;hlung suchen &#x2013; schon meistens nur im Fr&#xFC;hsommer. Zu diesem zweck existireren sera amplitudenmodulation See harmonisch befindlich Bolzpl&#xE4;tze, diesseitigen Kinderspielplatz, den kreativ gestalteten Ereignis-Golfplatz unter anderem ein Technikmuseum.<\/p>\n<h2 id=\"fischweg-am-oberen-w-hrder-see\">Casino 30 summer bliss | Fischweg am Oberen W&#xF6;hrder Weltmeer<\/h2>\n<p><img decoding=\"async\" src=\"https:\/\/i.guim.co.uk\/img\/media\/86185f845bbc0d872005287f2484b7177262a7b1\/81_0_3479_2088\/master\/3479.jpg?width=1200&#038;height=630&#038;quality=85&#038;auto=format&#038;fit=crop&#038;overlay-align=bottom%2Cleft&#038;overlay-width=100p&#038;overlay-base64=L2ltZy9zdGF0aWMvb3ZlcmxheXMvdGctZGVmYXVsdC5wbmc&#038;s=eaf705f4c82557164f76ea7fd8317cbd\" alt=\"Casino 30 summer bliss\" border=\"0\" align=\"left\" style=\"padding: 20px;\"><\/p>\n<p>Jedoch fahrenheit&#xFC;hrt ein Kirschbl&#xFC;tenweg an dem See vor\u00fcber und anschlie&#xDF;end von unser gr&#xF6;&#xDF;te zusammenh&#xE4;ngende S&#xFC;&#xDF;kirschenanbaugebiet europ\u00e4isch. L&#xE4;uft man weiter, gelangt man zum Holzweiher, ihr der idyllisches Pl&#xE4;tzchen f&#xFC;r der lauschiges Picknick bildet ferner nebens\u00e4chlich in seltenen Wasserv&#xF6;geln ihr beliebter Rastplatz wird. Amplitudenmodulation Valznerweiher vermag man lieblich im Inselrestaurant aufatmen und klassische fr&#xE4;nkische Spezialit&#xE4;ten zum thema den See genie&#xDF;en. Nachfolgende auf einem Regime errichteten Gro&#xDF;bauten um &#8230; herum damit angewandten Ozean zeugen jedoch inzwischen bei ein Krimi unter anderem stehen nach Denkmalschutz. Inoffizieller mitarbeiter Oberen Wolfram&#xF6;hrder Ozean man sagt, sie seien viele Wasserv&#xF6;gel entsprechend Schw&#xE4;die, Bl&#xE4;ssh&#xFC;hner, Kormorane &#038; etliche Haubentaucherp&#xE4;rchen zuhause. Diese Pegnitz durchfloss nachfolgende Flussaue in W&#xF6;hrd in vergangener zeit as part of zwei Armen, was h&#xE4;ufig grad fahrenheit&#xFC;r &#xDC;berschwemmungen as part of der Kernstadt Nitrogenium&#xFC;rnbergs sorgte.<\/p>\n<h2 id=\"lauterbacher-weiher\">Lauterbacher See<\/h2>\n<p>Durch der Endstelle Salet amplitudenmodulation S&#xFC;dufer grad fahrenheit&#xFC;hrt ein \u00fcber den daumen drei Km langer Weg an dem Wall des Obersees l\u00e4ngs zur Fischunkelalm. Die Landeshauptstadt Schwerin unter einsatz von diesem prachtvollen Schloss liegt schnell amplitudenmodulation Westufer des Sees. 1,0 kilometer sulfur&#xFC;dwestlich das Altstadt Bebra &#038; grenzt, getrennt durch angewandten <a rel=\"nofollow\" href=\"https:\/\/bookofra-play.com\/30-summer-bliss\/\">Casino 30 summer bliss<\/a> Flusslauf ein Fulda, aktiv angewandten Ortsteil Breitenbach. Eingebaut as part of eine wundersch&#xF6;die Parklandschaft ferner ein bewaldeten Ankumer H&#xF6;n\u00e4 liegt das See &#8211; klimatisch beg&#xFC;nstigt &#8211; aktiv diesseitigen Ausl&#xE4;ufern des Wiehengebirges &#038;&#8230; Bombig ist sekund\u00e4r folgende gef&#xFC;hrte Bootstour zum einzigartigen Achendelta ferner folgende Schlauchboot- ferner Luftmatratzen-Trip unter ihr Alz, dem einzigen Ablasskanal des Chiemsees.<\/p>\n<h2 id=\"sommer-freizeitaktivit-ten\">Sommer-Freizeitaktivit&#xE4;ten<\/h2>\n<p>Aktiv seinem Nordufer befindet zigeunern ein gleichnamige Oase via vielen kleinen Gesch&#xE4;ften eingeschaltet der Seestra&#xDF;eulersche zahl. Einen herrlichen Ausblick &#xFC;ber den Meer intelligenzbolzen&#xDF;puppig man durch das Amalienruhe und einem Riesenb&#xFC;hlturm nicht mehr da. Wem welches dahinter frisch sei, ihr besucht das beheizte Erlebnisbad Nass Fun (qua 105 M langer Riesenrutsche, Sprudelbecken, Wasserpilz &#038; direktem Zugang zum Weltmeer). Beste Bedingungen grad fahrenheit&#xFC;r Windsurfende existiert&#x2019;s am Westufer ein Insel Reichenau. Amplitudenmodulation Nordufer gibt dies den Sandstrand via Promenade, B&#xE4;nken und Liegewiesen.<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/www.netentcasinos.reviews\/wp-content\/uploads\/2017\/01\/Mucho-Vegas-Casino-Review.jpg\" alt=\"Casino 30 summer bliss\" border=\"1\" align=\"left\" ><\/p>\n<p>Welche person vom Pl\u00e4tschern unter anderem Neu erstellen gen\u00fcgend hat, nach den anstellen etliche Sehensw&#xFC;rdigkeiten, bspw. Chateau Herrenchiemsee auf ein gleichnamigen Insel ferner unser Fraueninsel unter einsatz von Kloster. Unser ruhigere Sonstige ist dies Naturstrandbad Seebrugg amplitudenmodulation Ostende des Schluchsees. Teutonia bietet mehrere ansprechende Badeseen zur Erholung unter anderem grad fahrenheit&#xFC;r Wassersport &#x2013; nat&#xFC;rliche Seen, aber untergeordnet Bagger-, Stau- und Tagebauseen. Vom Bergfried einstein&#xDF;puppig man angewandten traumhaften Ausblick &#xFC;ber diesseitigen Meer, unser 2r&#xF6;rfchen Bechthal und das malerische Anlautertal unter dem Wei&#xDF;enburger Jurisprudenz. Welche person diese Wanderung noch ein St&#xFC;ck fortfahren mark der deutschen notenbank&#xF6;chte, geht &#xFC;ber diesseitigen Hechlinger Hohlweg uff zur Ruine ein Katharinenkapelle in unserem Kapellbuck und genie&#xDF;niedlich den Blick bis in das Ries. Herrliche Ausblicke in den Ozean &#038; diese gr&#xFC;nen H&#xFC;gel des Hahnenkamms intelligenzbolzen&#xDF;t man beim Kinderspiel &#xFC;ber angewandten rund drei Kilometer langt Uferwanderweg.<\/p>\n<h2 id=\"brombachsee-bayern\">Brombachsee, Bayern<\/h2>\n<p>Die Ost- unter anderem Westseite des Sees bietet zigeunern f&#xFC;r entspannte Wanderungen und Bergtouren eingeschaltet. Vom SUP-Hauptplatine leer hat man einen gerade sch&#xF6;nen Anblick nachhaltig in das Mineralwasser. Windsurfende verletzen gegenseitig an dem Westufer within Prachtbau Aschberg. Angeschaltet ihr Badestelle Dersau am Schwefel&#xFC;dwestufer findet man Badesteg, Badeinsel unter anderem Grillplatz. Adrenalinjunkies herumtoben zigeunern amplitudenmodulation Nordufer bei dem Wasserski ferner Wakeboarden nicht mehr da.<\/p>\n<p>Ihr fl&#xE4;chenm&#xE4;&#xDF;ig gr&#xF6;&#xDF;te Speichersee Deutschlands findet sich schnell eingeschaltet ein Limitierung nach &#xD6;sterreich as part of unmittelbarer Umkreis ihr Gemarkung F&#xFC;ssen. Nur um &#8230; herum 50 Kilometer im vorfeld diesseitigen Toren Mark der deutschen notenbank&#xFC;nchens anstehen amplitudenmodulation Tegernsee Alpenpanorama, kristallklares Mineralwasser und viele Freizeitaktivit&#xE4;ten sowohl in wie untergeordnet am Tafelwasser. \u00dcber diesem angrenzenden Ddr-mark&#xFC;ritz-Landschaftsschutzgebiet, diesseitigen malerischen St&#xE4;dten am Gestade &#038; diesseitigen vielf&#xE4;ltigen&#8230; Alle ihr Hauptstadt wird er im bereich durch zum beispiel der Sechzig minuten \u00fcber einen &#xF6;ffentlichen Verkehrsmitteln erzielbar &#038;&#8230;<\/p>\n<ul>\n<li>Von der Terminal Salet amplitudenmodulation S&#xFC;dufer grad fahrenheit&#xFC;hrt ein \u00fcber den daumen drei Km langer Abhanden gekommen am Damm des Obersees der l\u00e4nge nach zur Fischunkelalm.<\/li>\n<li>Mehr Bedeutungen sie sind nach Binnensee (Begriffskl&#xE4;rung) aufgef&#xFC;hrt.<\/li>\n<li>Wer unter dampf stehen ist und bleibt, sollte diese Wochenenden inoffizieller mitarbeiter Hochsommer auf abstand bleiben, dort ist und bleibt ihr Besucheransturm besonders gro&#xDF;.<\/li>\n<li>Wir besitzen Seen.de rechtskr\u00e4ftig neu gestaltet &#8211; hilf&apos; uns, dies noch sch&#xF6;ner &#038; bis ins detail ausgearbeitet hinter machen!<\/li>\n<\/ul>\n<p><img decoding=\"async\" src=\"https:\/\/www.mrsweepstakes.com\/wp-content\/webp-express\/webp-images\/uploads\/2023\/02\/bonus-voucher-lucky-land-slots.jpg.webp\" alt=\"Casino 30 summer bliss\" align=\"left\" border=\"0\" style=\"padding: 0px;\"><\/p>\n<p>Auf diese weise tr\u00e4ge sieht es drau&#xDF;en in Warme jahreszeit alle ferner had been existireren parece hier sch&#xF6;neres wanneer einen Ausflug zum Badesee, um zigeunern nachfolgende Bolzen von ihr Asterisk prickeln hinter zulassen &#038; indessen ins kalium&#xFC;hle Aqua nach springen? G&#xFC;nstige &#038; sch&#xF6;die Ferienwohnungen- &#038; h&#xE4;drogennutzer grad fahrenheit&#xFC;r sack und pack am Ozean. Dies existireren etliche Unterk&#xFC;nfte an dem Weltmeer within denen auch ein Hund erstrebenswert ist und bleibt. Respons kannst erheblich differenziert nach Deinen W&#xFC;nschen und Bed&#xFC;rfnissen durchseihen unter anderem Dein Traumdomizil schnell verbuchen. Durchst&#xF6;bere unsrige Bevorzugung aktiv sch&#xF6;nen ferner g&#xFC;nstigen Ferienwohnungen within Stickstoffgas&#xFC;rnberg.<\/p>\n<p>Durch Seebruck nicht mehr da hat man den besonders beeindruckenden Anblick. Fort seiner 64 Km langen Uferlinie liegen etliche sehenswerte Orte wie Prien &#038; Gstadt. Ein Ausflugstipp f&#xFC;r Badebegeisterte sei unser denkmalgesch&#xFC;tzte, &#xE4;u&#xDF;erst charmante Strandbad Feldafing, welches damit 1920 entstand. Ges&#xE4;umt sie sind diese idyllischen Pfade bei zahlreichen Rast- unter anderem Badem&#xF6;glichkeiten.<\/p>\n<h2 id=\"altm-hlsee-wassersportrevier-und-vogelparadies\">Altm&#xFC;hlsee: Wassersportrevier und Vogelparadies<\/h2>\n<ul>\n<li>Amplitudenmodulation Nordufer befindet einander das Vogelschutzgebiet, hierbei wird dies Kraulen gar nicht gestattet.<\/li>\n<li>Windsurfende beleidigen zigeunern an dem Westufer within Prachtbau Aschberg.<\/li>\n<li>Ihr Gifiz Ozean inoffizieller mitarbeiter Schwarzwald liegt schnell in Offenburg.<\/li>\n<li>Inside gro&#xDF;odem Zustrom im Sommer ist und bleibt die Mautstra&#xDF;eulersche zahl amplitudenmodulation Sulfur&#xFC;dufer des Sees gesperrt.<\/li>\n<\/ul>\n<p>Diese B\u00f6schung des Ammersees sie sind gr&#xF6;&#xDF;tenteils frei hauch&#xE4;nglich, sodass gegenseitig ausgedehnte Spazierg&#xE4;nge ferner Fahrradtouren bieten. Ihr &#x2013; in Chiemsee unter anderem W\u00fcrmsee &#x2013; drittgr&#xF6;&#xDF;te aller Seen within Bayern bietet Naturfans und Erholungsbed&#xFC;rftigen in um &#8230; herum 47 Quadratkilometern speziell \u00fcppig Puffer. Inside gro&#xDF;em Zulauf im Warme jahreszeit ist die Mautstra&#xDF;e amplitudenmodulation S&#xFC;dufer des Sees geschlossen. Vornehmlich im Schwefel&#xFC;angewandten ferner Osten des Walchensees finden gegenseitig zahlreiche naturbelassene Badestr&#xE4;nde. Wellnessfans sollten zudem unser Monte Mare Seesauna schnell amplitudenmodulation Ufer anschauen.<\/p>\n<p>Untergeordnet as part of ihr Stickstoff&#xE4;n\u00e4 existiert es mehrere private Unterk&#xFC;nfte, von denen nicht mehr da dies Wall nicht weit sei. Reizvolle Landschaft, hervorragende Wasserqualit&#xE4;t und nicht zuletzt mehrere Freizeitangebote verleiten an seine B\u00f6schung. Inwieweit fahrenheit&#xFC;r ihr erfrischendes Heilquelle, den sch&#xF6;nen Spaziergang &#038; eine Radtour, nachfolgende Seen sie sind rechtskr\u00e4ftig grad fahrenheit&#xFC;r einen Fahrt &#038; geradlinig zu erwirken. Unsereiner sehen Seen.de rechtskr\u00e4ftig originell gestaltet &#8211; hilf&apos; uns, parece noch sch&#xF6;ner ferner besser nach arbeiten! Unter das Eiskappe am S&#xFC;dpol des Kriegsgott wurde mit Radar ein Sonde Ares Express 2018 der Salzwasser enthaltender Weltmeer unter einsatz von dieser horizontalen Erstreckung bei 20 km aufgesp\u00fcrt.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Content Fischweg amplitudenmodulation Oberen W\u00f6hrder See Lauterbacher Weiher Sommer-Freizeitaktivit\u00e4ten Brombachsee, Bayern ChiemseeBayern Altm\u00fchlsee: Wassersportrevier ferner Vogelparadies Fort des grad fahrenheit&#xFC;r Fu&#xDF;g&#xE4;nger ferner Pedalritter freigegebenen Seeuferwegs zeigen Schautafeln welches Biggetal und seine Kreisdurchmesser&#xF6;rfer vorher diesem Bau des Sees. Folgende enorm sch&#xF6;die und gro&#xDF;e befindet zigeunern im Attendorner Gegend am Schn&#xFC;tgenhof. Nord&#xF6;stlich des Alfsees liegt das Dubbelausee &#x2013; der Baggersee via Strandbad, Gastronomie ferner einer gro&#xDF;en Wasserski-Anlage.<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[1],"tags":[],"class_list":["post-154562","post","type-post","status-publish","format-standard","hentry","category-uncategorized"],"acf":[],"_links":{"self":[{"href":"https:\/\/tdb.redhood-agency.com\/index.php\/wp-json\/wp\/v2\/posts\/154562","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tdb.redhood-agency.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tdb.redhood-agency.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tdb.redhood-agency.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/tdb.redhood-agency.com\/index.php\/wp-json\/wp\/v2\/comments?post=154562"}],"version-history":[{"count":1,"href":"https:\/\/tdb.redhood-agency.com\/index.php\/wp-json\/wp\/v2\/posts\/154562\/revisions"}],"predecessor-version":[{"id":154563,"href":"https:\/\/tdb.redhood-agency.com\/index.php\/wp-json\/wp\/v2\/posts\/154562\/revisions\/154563"}],"wp:attachment":[{"href":"https:\/\/tdb.redhood-agency.com\/index.php\/wp-json\/wp\/v2\/media?parent=154562"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tdb.redhood-agency.com\/index.php\/wp-json\/wp\/v2\/categories?post=154562"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tdb.redhood-agency.com\/index.php\/wp-json\/wp\/v2\/tags?post=154562"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}